{"id":18826,"date":"2024-11-06T16:49:41","date_gmt":"2024-11-06T15:49:41","guid":{"rendered":"https:\/\/riding.zandona.net\/shop\/unkategorisiert\/carbon-pro-h-performance-ex-fetlock\/"},"modified":"2026-03-20T10:36:50","modified_gmt":"2026-03-20T09:36:50","slug":"carbon-pro-h-performance-ex-fetlock","status":"publish","type":"product","link":"https:\/\/riding.zandona.net\/de\/shop\/auslass\/gamaschen-de\/carbon-pro-ex-protezioni-cavallo-in-promozione_de\/carbon-pro-h-performance-ex-fetlock\/","title":{"rendered":"CARBON PRO H-PERFORMANCE eX Fetlock"},"content":{"rendered":"<p>Die Streichkappen &#8220;CARBON PRO H-PERFORMANCE eX Fetlock&#8221; wurden ausschlie\u00dflich f\u00fcr den Einsatz im Wettkampf entwickelt, denn dank einer anderen Form der Struktur entlang der Sehne, ohne den Komfort und das Wohlbefinden des Pferdes zu beeintr\u00e4chtigen, k\u00f6nnen sie Pferden helfen, die Schwierigkeiten haben, mit den Hinterbeinen zu springen.<\/p>\n<p>Sie sind idealen und notwendigen f\u00fcr Pferde, die dazu neigen, mit Eisen auf den Pferd-Fessel des gegen\u00fcberliegenden Gliedes zu schlagen. Sie sind n\u00e4mlich mit einer ergonomischen Erweiterung der Neopren Polsterung, ausgestattet die mit einer verschlei\u00dffesten Folie in Carbon-Optik beschichtet ist.<\/p>\n<p>Diese Streichkappen wurden mit einem grundlegenden \u00fcberarbeiteten Design neu gestaltet, um dem Pferd noch leichtere und atmungsaktivere Gamaschen und einen noch umfassenderen Schutzbereich zu bieten.<\/p>\n<p>Die noch st\u00e4rkeren und breiteren Kohlenstofffasern, bilden eine thermische Barriere, die die Gelenke des Pferdes vor der durch das Scheuern entstehenden Hitze sch\u00fctzt und gleichzeitig die Sto\u00dffestigkeit erh\u00f6ht.<\/p>\n<p>Die Polsterung bestehend aus einer Au\u00dfenschicht aus 3D-Air-Mesh, einer Innenschicht aus perforiertem Neopren und dem getesteten Gel-Tech f\u00fcr die Bereiche, die am st\u00e4rksten dem St\u00f6\u00dfen ausgesetzt sind.<\/p>\n<p>Die neuen Gurten wurden mit einem modernen Design neu gestaltet und f\u00fcr ein schnelleres L\u00f6sen und Befestigen sowie eine h\u00f6here Festigkeit bequemer und funktioneller gemacht.<\/p>\n<p>Schlie\u00dflich garantiert die bew\u00e4hrte Flex-Zone weiterhin eine gro\u00dfe Bewegungsfreiheit f\u00fcr die Gliedma\u00dfen.<\/p>\n<p>100% Made in Italy und nachhaltig, da es aus 95% recyceltem TPU (PSV-zertifiziert) hergestellt wird.<\/p>\n<p>HAUPTMERKMALE:<br \/>\n&#8211; Eins\u00e4tze in Kohlenstofffaser f\u00fcr zus\u00e4tzlichen Schutz;<br \/>\n&#8211; Ergonomische Erweiterung der Neopren Polsterung;<br \/>\n&#8211; Anatomische Struktur aus recyceltem TPU;<br \/>\n&#8211; 3D Air-Mesh + perforiertes Neopren;<br \/>\n&#8211; Gel-Tech Polsterung f\u00fcr Sto\u00dfd\u00e4mpfung;<br \/>\n&#8211; Lufteinl\u00e4sse f\u00fcr zus\u00e4tzliche Bel\u00fcftung;<br \/>\n&#8211; Flex-Zone f\u00fcr v\u00f6llige Bewegungsfreiheit;<br \/>\n&#8211; Der Verschluss wird durch elastische Gurte mit Schnellverschluss gew\u00e4hrleistet;<br \/>\n&#8211; 100% Made in Italy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fesselgelenkschutz (Performance Boots)<\/p>\n","protected":false},"featured_media":36883,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3555,3974,3731,3695],"product_tag":[],"class_list":{"0":"post-18826","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-auslass","7":"product_cat-carbon-pro-ex-protezioni-cavallo-in-promozione_de","8":"product_cat-fei-konforme-streichkappen","9":"product_cat-gamaschen-de","10":"pa_codice-intrastat-42010000-de","11":"pa_disciplina-utilizzo-harness","12":"pa_disciplina-utilizzo-springreiten","13":"pa_disciplina-utilizzo-trekking-de","14":"pa_giro-nodello-da-28-a-30-cm-de","15":"pa_giro-nodello-da-31-a-32-cm-de","16":"pa_giro-nodello-da-33-a-34-cm-de","17":"pa_giro-nodello-da-35-a-37-cm-de","19":"first","20":"instock","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/riding.zandona.net\/de\/wp-json\/wp\/v2\/product\/18826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riding.zandona.net\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/riding.zandona.net\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/riding.zandona.net\/de\/wp-json\/wp\/v2\/comments?post=18826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riding.zandona.net\/de\/wp-json\/wp\/v2\/media\/36883"}],"wp:attachment":[{"href":"https:\/\/riding.zandona.net\/de\/wp-json\/wp\/v2\/media?parent=18826"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/riding.zandona.net\/de\/wp-json\/wp\/v2\/product_brand?post=18826"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/riding.zandona.net\/de\/wp-json\/wp\/v2\/product_cat?post=18826"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/riding.zandona.net\/de\/wp-json\/wp\/v2\/product_tag?post=18826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}