{"id":22264,"date":"2024-11-06T16:50:22","date_gmt":"2024-11-06T15:50:22","guid":{"rendered":"https:\/\/riding.zandona.net\/shop\/sin categor\u00eda\/carbon-pro-techno-fur-tendon\/"},"modified":"2024-11-07T13:49:27","modified_gmt":"2024-11-07T12:49:27","slug":"carbon-pro-techno-fur-tendon","status":"publish","type":"product","link":"https:\/\/riding.zandona.net\/es\/shop\/caballo\/protectores-de-caballo\/salto-de-obstaculos\/carbon-pro-techno-fur-es\/carbon-pro-techno-fur-tendon\/","title":{"rendered":"CARBON PRO TECHNO-FUR Tendon"},"content":{"rendered":"<p>El protector de tend\u00f3n CARBON PRO TECHNO-FUR tendon se caracteriza por el forro de Piel Artificial (Techno-Fur).<br \/>\nLa piel artificial no es un termorregulador natural y no tiene las mismas propiedades que la lana real, pero es la opci\u00f3n ideal para quienes buscan un protector de caballo esponjoso y f\u00e1cil de limpiar.<br \/>\nEstos protectores para caballos han sido redise\u00f1ados con un dise\u00f1o profundamente revisado para ser a\u00fan m\u00e1s livianos y brindar un \u00e1rea de protecci\u00f3n m\u00e1s completa.<br \/>\nLa innovadora estructura, inspirada en los coches de carreras y los aviones, presenta grandes tomas de aire estrat\u00e9gicamente situadas, por primera vez, frontalmente en la direcci\u00f3n del movimiento del caballo. Gracias a esto, el aire canalizado bajo la calota es expulsado m\u00e1s abundantemente a trav\u00e9s de una entrada de aire central espec\u00edfica en la zona donde se produce un efecto de &#8220;succi\u00f3n&#8221; debido a la relativa depresi\u00f3n que se genera t\u00edpicamente en la parte trasera de los veh\u00edculos\/objetos en movimiento. Una innovaci\u00f3n sin igual en el mercado para controlar el estr\u00e9s articular provocado por el calor y reducir el riesgo de lesiones.<br \/>\nLos elementos de Fibra de Carbono, a\u00fan m\u00e1s resistentes y extensos, crean una barrera t\u00e9rmica para proteger las articulaciones del caballo del calor generado por la fricci\u00f3n y aumentar la resistencia a los impactos y el probado Gel-Tech ayuda a proteger las zonas m\u00e1s expuestas a los impactos.<br \/>\nLas nuevas hebillas tipo perno han sido redise\u00f1adas con un dise\u00f1o moderno y se han hecho m\u00e1s c\u00f3modas y funcionales para un cierre y liberaci\u00f3n r\u00e1pidos y una mayor durabilidad.<br \/>\nPor \u00faltimo, la probada Flex-Zone sigue garantizando la m\u00e1xima libertad de movimiento de la extremidad.<br \/>\n100% Made in Italy y sostenible ya que est\u00e1 fabricado con un 95% de TPU reciclado (certificado PSV).<\/p>\n<p>CARACTER\u00cdSTICAS PRINCIPALES:<br \/>\n&#8211; Inserciones de fibra de carbono para mayor protecci\u00f3n;<br \/>\n&#8211; Estructura Anat\u00f3mica en TPU Reciclado;<br \/>\n&#8211; Forro de lana artificial Techno-Fur;<br \/>\n&#8211; Acolchado Gel-Tech para absorci\u00f3n de impactos;<br \/>\n&#8211; Mayores entradas de aire para ventilaci\u00f3n adicional;<br \/>\n&#8211; Flex-Zone para una total libertad de movimiento;<br \/>\n&#8211; Fijaci\u00f3n segura garantizada mediante correas el\u00e1sticas con puntas de f\u00e1cil clip para una liberaci\u00f3n r\u00e1pida;<br \/>\n&#8211; 100% Hecho en Italia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Protecci\u00f3n de tendones<\/p>\n","protected":false},"featured_media":12516,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3644,3637,3648,3652],"product_tag":[],"class_list":{"0":"post-22264","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-caballo","7":"product_cat-carbon-pro-techno-fur-es","8":"product_cat-protectores-de-caballo","9":"product_cat-salto-de-obstaculos","10":"pa_codice-intrastat-42010000-es","11":"pa_disciplina-utilizzo-salto-de-obstaculos","12":"pa_disciplina-utilizzo-trekking-es","13":"pa_disciplina-utilizzo-trot-es","14":"pa_giro-nodello-da-26-a-28-cm-es","15":"pa_giro-nodello-da-29-a-30-cm-es","16":"pa_giro-nodello-da-31-a-32-cm-es","17":"pa_giro-nodello-da-33-a-35-cm-es","19":"first","20":"instock","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/riding.zandona.net\/es\/wp-json\/wp\/v2\/product\/22264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riding.zandona.net\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/riding.zandona.net\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/riding.zandona.net\/es\/wp-json\/wp\/v2\/comments?post=22264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riding.zandona.net\/es\/wp-json\/wp\/v2\/media\/12516"}],"wp:attachment":[{"href":"https:\/\/riding.zandona.net\/es\/wp-json\/wp\/v2\/media?parent=22264"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/riding.zandona.net\/es\/wp-json\/wp\/v2\/product_brand?post=22264"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/riding.zandona.net\/es\/wp-json\/wp\/v2\/product_cat?post=22264"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/riding.zandona.net\/es\/wp-json\/wp\/v2\/product_tag?post=22264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}